{"id":11219,"date":"2024-03-30T22:52:24","date_gmt":"2024-03-31T02:52:24","guid":{"rendered":"https:\/\/www.fetepouremporter.com\/?post_type=product&#038;p=11219"},"modified":"2024-04-07T12:11:05","modified_gmt":"2024-04-07T16:11:05","slug":"ballon-en-latex-transparent-avec-confettis-argent-17-pouces","status":"publish","type":"product","link":"https:\/\/www.fetepouremporter.com\/en\/produit\/ballon-en-latex-transparent-avec-confettis-argent-17-pouces\/","title":{"rendered":"BALLON EN LATEX TRANSPARENT AVEC CONFETTIS ARGENT 17 POUCES"},"content":{"rendered":"<p><span style=\"color: #ff0000;\">Veuillez prendre note que les ballons achet\u00e9s en ligne ne sont pas gonfl\u00e9s.<\/span><\/p>\n<ul>\n<li>Tous nos ballons en latex sont de qualit\u00e9s sup\u00e9rieurs et biod\u00e9gradables<\/li>\n<li>Les ballons en latex peuvent \u00eatre gonfl\u00e9s \u00e0 l&#8217;air ou \u00e0 l&#8217;h\u00e9lium<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Voici le parfait ballon qui ajoutera une belle touche festive et color\u00e9e \u00e0 vos \u00e9v\u00e9nements. Laissez parler votre c\u00f4t\u00e9 cr\u00e9atif et cr\u00e9ez une ambiance compl\u00e8tement d\u00e9jant\u00e9e!<\/p>\n","protected":false},"featured_media":7363,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[96,162],"product_tag":[],"class_list":["post-11219","product","type-product","status-publish","has-post-thumbnail","product_cat-ballons-en","product_cat-latex-transparent-avec-confettis-en","pa_format-10-pcs-en","pa_format-2-pcs-en","pa_format-25-pcs-en","pa_format-5-pcs-en","pa_format-50-pcs-en","pa_format-unite-en","pa_taille-11-pouces-en","pa_taille-17-pouces-en","pa_taille-24-pouces-en","pa_taille-5-pouces-en","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BALLON EN LATEX TRANSPARENT AVEC CONFETTIS ARGENT 17 POUCES - F\u00eate pour emporter<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fetepouremporter.com\/en\/produit\/ballon-en-latex-transparent-avec-confettis-argent-17-pouces\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BALLON EN LATEX TRANSPARENT AVEC CONFETTIS ARGENT 17 POUCES - F\u00eate pour emporter\" \/>\n<meta property=\"og:description\" content=\"Voici le parfait ballon qui ajoutera une belle touche festive et color\u00e9e \u00e0 vos \u00e9v\u00e9nements. Laissez parler votre c\u00f4t\u00e9 cr\u00e9atif et cr\u00e9ez une ambiance compl\u00e8tement d\u00e9jant\u00e9e!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fetepouremporter.com\/en\/produit\/ballon-en-latex-transparent-avec-confettis-argent-17-pouces\/\" \/>\n<meta property=\"og:site_name\" content=\"F\u00eate pour emporter\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-07T16:11:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fetepouremporter.com\/wp-content\/uploads\/2024\/03\/Ballon-confetti-argent.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fetepouremporter.com\\\/en\\\/produit\\\/ballon-en-latex-transparent-avec-confettis-argent-17-pouces\\\/\",\"url\":\"https:\\\/\\\/www.fetepouremporter.com\\\/en\\\/produit\\\/ballon-en-latex-transparent-avec-confettis-argent-17-pouces\\\/\",\"name\":\"BALLON EN LATEX TRANSPARENT AVEC CONFETTIS ARGENT 17 POUCES - F\u00eate pour emporter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fetepouremporter.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fetepouremporter.com\\\/en\\\/produit\\\/ballon-en-latex-transparent-avec-confettis-argent-17-pouces\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fetepouremporter.com\\\/en\\\/produit\\\/ballon-en-latex-transparent-avec-confettis-argent-17-pouces\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fetepouremporter.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Ballon-confetti-argent.jpg\",\"datePublished\":\"2024-03-31T02:52:24+00:00\",\"dateModified\":\"2024-04-07T16:11:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fetepouremporter.com\\\/en\\\/produit\\\/ballon-en-latex-transparent-avec-confettis-argent-17-pouces\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fetepouremporter.com\\\/en\\\/produit\\\/ballon-en-latex-transparent-avec-confettis-argent-17-pouces\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fetepouremporter.com\\\/en\\\/produit\\\/ballon-en-latex-transparent-avec-confettis-argent-17-pouces\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fetepouremporter.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Ballon-confetti-argent.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fetepouremporter.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Ballon-confetti-argent.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fetepouremporter.com\\\/en\\\/produit\\\/ballon-en-latex-transparent-avec-confettis-argent-17-pouces\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.fetepouremporter.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.fetepouremporter.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BALLON EN LATEX TRANSPARENT AVEC CONFETTIS ARGENT 17 POUCES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fetepouremporter.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.fetepouremporter.com\\\/en\\\/\",\"name\":\"F\u00eate pour emporter\",\"description\":\"Nous avons bien h\u00e2te d&#039;organiser votre \u00e9v\u00e8nement !\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fetepouremporter.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fetepouremporter.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fetepouremporter.com\\\/en\\\/#organization\",\"name\":\"F\u00eate pour emporter\",\"url\":\"https:\\\/\\\/www.fetepouremporter.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fetepouremporter.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fetepouremporter.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/cropped-logo_fpe.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fetepouremporter.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/cropped-logo_fpe.jpg\",\"width\":642,\"height\":642,\"caption\":\"F\u00eate pour emporter\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fetepouremporter.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BALLON EN LATEX TRANSPARENT AVEC CONFETTIS ARGENT 17 POUCES - F\u00eate pour emporter","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fetepouremporter.com\/en\/produit\/ballon-en-latex-transparent-avec-confettis-argent-17-pouces\/","og_locale":"en_US","og_type":"article","og_title":"BALLON EN LATEX TRANSPARENT AVEC CONFETTIS ARGENT 17 POUCES - F\u00eate pour emporter","og_description":"Voici le parfait ballon qui ajoutera une belle touche festive et color\u00e9e \u00e0 vos \u00e9v\u00e9nements. Laissez parler votre c\u00f4t\u00e9 cr\u00e9atif et cr\u00e9ez une ambiance compl\u00e8tement d\u00e9jant\u00e9e!","og_url":"https:\/\/www.fetepouremporter.com\/en\/produit\/ballon-en-latex-transparent-avec-confettis-argent-17-pouces\/","og_site_name":"F\u00eate pour emporter","article_modified_time":"2024-04-07T16:11:05+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.fetepouremporter.com\/wp-content\/uploads\/2024\/03\/Ballon-confetti-argent.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fetepouremporter.com\/en\/produit\/ballon-en-latex-transparent-avec-confettis-argent-17-pouces\/","url":"https:\/\/www.fetepouremporter.com\/en\/produit\/ballon-en-latex-transparent-avec-confettis-argent-17-pouces\/","name":"BALLON EN LATEX TRANSPARENT AVEC CONFETTIS ARGENT 17 POUCES - F\u00eate pour emporter","isPartOf":{"@id":"https:\/\/www.fetepouremporter.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fetepouremporter.com\/en\/produit\/ballon-en-latex-transparent-avec-confettis-argent-17-pouces\/#primaryimage"},"image":{"@id":"https:\/\/www.fetepouremporter.com\/en\/produit\/ballon-en-latex-transparent-avec-confettis-argent-17-pouces\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fetepouremporter.com\/wp-content\/uploads\/2024\/03\/Ballon-confetti-argent.jpg","datePublished":"2024-03-31T02:52:24+00:00","dateModified":"2024-04-07T16:11:05+00:00","breadcrumb":{"@id":"https:\/\/www.fetepouremporter.com\/en\/produit\/ballon-en-latex-transparent-avec-confettis-argent-17-pouces\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fetepouremporter.com\/en\/produit\/ballon-en-latex-transparent-avec-confettis-argent-17-pouces\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fetepouremporter.com\/en\/produit\/ballon-en-latex-transparent-avec-confettis-argent-17-pouces\/#primaryimage","url":"https:\/\/www.fetepouremporter.com\/wp-content\/uploads\/2024\/03\/Ballon-confetti-argent.jpg","contentUrl":"https:\/\/www.fetepouremporter.com\/wp-content\/uploads\/2024\/03\/Ballon-confetti-argent.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.fetepouremporter.com\/en\/produit\/ballon-en-latex-transparent-avec-confettis-argent-17-pouces\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.fetepouremporter.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.fetepouremporter.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"BALLON EN LATEX TRANSPARENT AVEC CONFETTIS ARGENT 17 POUCES"}]},{"@type":"WebSite","@id":"https:\/\/www.fetepouremporter.com\/en\/#website","url":"https:\/\/www.fetepouremporter.com\/en\/","name":"F\u00eate pour emporter","description":"Nous avons bien h\u00e2te d&#039;organiser votre \u00e9v\u00e8nement !","publisher":{"@id":"https:\/\/www.fetepouremporter.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fetepouremporter.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.fetepouremporter.com\/en\/#organization","name":"F\u00eate pour emporter","url":"https:\/\/www.fetepouremporter.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fetepouremporter.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.fetepouremporter.com\/wp-content\/uploads\/2021\/08\/cropped-logo_fpe.jpg","contentUrl":"https:\/\/www.fetepouremporter.com\/wp-content\/uploads\/2021\/08\/cropped-logo_fpe.jpg","width":642,"height":642,"caption":"F\u00eate pour emporter"},"image":{"@id":"https:\/\/www.fetepouremporter.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.fetepouremporter.com\/en\/wp-json\/wp\/v2\/product\/11219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fetepouremporter.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.fetepouremporter.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fetepouremporter.com\/en\/wp-json\/wp\/v2\/media\/7363"}],"wp:attachment":[{"href":"https:\/\/www.fetepouremporter.com\/en\/wp-json\/wp\/v2\/media?parent=11219"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.fetepouremporter.com\/en\/wp-json\/wp\/v2\/product_brand?post=11219"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.fetepouremporter.com\/en\/wp-json\/wp\/v2\/product_cat?post=11219"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.fetepouremporter.com\/en\/wp-json\/wp\/v2\/product_tag?post=11219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}